{"id":22386,"date":"2024-12-13T11:12:11","date_gmt":"2024-12-13T09:12:11","guid":{"rendered":"https:\/\/academy.police.md\/?p=22386"},"modified":"2024-12-13T11:13:18","modified_gmt":"2024-12-13T09:13:18","slug":"activitati-de-informare","status":"publish","type":"post","link":"https:\/\/academy.police.md\/gb\/activitati-de-informare","title":{"rendered":"Activit\u0103\u0163i de informare"},"content":{"rendered":"\n<p>\u00cen contextul Zilei Interna\u021bionale Anticorup\u021bie, \u00een cadrul Direc\u0163iei CIPAL, la data de 12 decembrie 2024 au fost organizate activit\u0103\u0163i de informare \u00een domeniul integrit\u0103\u021bii. Sesiunea a fost desf\u0103\u0219urat\u0103 de c\u0103tre formatorii din cadrul Academiei \u201e\u0218tefan cel Mare\u201d, Serviciului protec\u021bie intern\u0103 \u0219i anticorup\u021bie \u0219i al Inspectoratului General al Poli\u021biei, cu suportul Centrului de la Geneva pentru Guvernarea Sectorului de Securitate (DCAF).<\/p>\n\n\n\n<p>Beneficiari ai instruirii au fost 36 de angaja\u021bi din cadrul Inspectoratului General al Poli\u021biei care au abordat subiecte ce \u0163in de manifest\u0103rile de corup\u021bie cu implicarea angaja\u021bilor MAI, rolul avertizorilor de integritate \u0219i comunicarea eficient\u0103 \u00een context profesional \u0219i \u00een situa\u021bii de criz\u0103, cu scopul de a consolida integritatea profesional\u0103.<\/p>\n\n\n\n<p>Astfel de activit\u0103\u0163i sunt imperative \u00een promovarea unei culturi organiza\u021bionale bazate pe integritate, contribuind astfel la \u00eembun\u0103t\u0103\u021birea performan\u021bei \u0219i transparen\u021bei \u00een activitatea personalului din cadrul subdiviziunilor MAI.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"\/wp-content\/uploads\/2024\/12\/IMG_20241212_092433-768x1024.jpg\" alt=\"\" data-id=\"22388\" data-full-url=\"\/wp-content\/uploads\/2024\/12\/IMG_20241212_092433-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=22388\" class=\"wp-image-22388\" srcset=\"\/wp-content\/uploads\/2024\/12\/IMG_20241212_092433-768x1024.jpg 768w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_092433-225x300.jpg 225w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_092433-1152x1536.jpg 1152w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_092433-1536x2048.jpg 1536w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_092433-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"\/wp-content\/uploads\/2024\/12\/IMG_20241212_092519-1-1024x768.jpg\" alt=\"\" data-id=\"22389\" data-full-url=\"\/wp-content\/uploads\/2024\/12\/IMG_20241212_092519-1-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=22389\" class=\"wp-image-22389\" srcset=\"\/wp-content\/uploads\/2024\/12\/IMG_20241212_092519-1-1024x768.jpg 1024w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_092519-1-300x225.jpg 300w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_092519-1-768x576.jpg 768w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_092519-1-1536x1152.jpg 1536w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_092519-1-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"\/wp-content\/uploads\/2024\/12\/IMG_20241212_092710-768x1024.jpg\" alt=\"\" data-id=\"22390\" data-full-url=\"\/wp-content\/uploads\/2024\/12\/IMG_20241212_092710-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=22390\" class=\"wp-image-22390\" srcset=\"\/wp-content\/uploads\/2024\/12\/IMG_20241212_092710-768x1024.jpg 768w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_092710-225x300.jpg 225w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_092710-1152x1536.jpg 1152w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_092710-1536x2048.jpg 1536w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_092710-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"\/wp-content\/uploads\/2024\/12\/IMG_20241212_101217-768x1024.jpg\" alt=\"\" data-id=\"22391\" data-full-url=\"\/wp-content\/uploads\/2024\/12\/IMG_20241212_101217-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=22391\" class=\"wp-image-22391\" srcset=\"\/wp-content\/uploads\/2024\/12\/IMG_20241212_101217-768x1024.jpg 768w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_101217-225x300.jpg 225w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_101217-1152x1536.jpg 1152w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_101217-1536x2048.jpg 1536w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_101217-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"\/wp-content\/uploads\/2024\/12\/IMG_20241212_105406-768x1024.jpg\" alt=\"\" data-id=\"22392\" data-full-url=\"\/wp-content\/uploads\/2024\/12\/IMG_20241212_105406-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=22392\" class=\"wp-image-22392\" srcset=\"\/wp-content\/uploads\/2024\/12\/IMG_20241212_105406-768x1024.jpg 768w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_105406-225x300.jpg 225w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_105406-1152x1536.jpg 1152w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_105406-1536x2048.jpg 1536w, \/wp-content\/uploads\/2024\/12\/IMG_20241212_105406-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00cen contextul Zilei Interna\u021bionale Anticorup\u021bie, \u00een cadrul Direc\u0163iei CIPAL, la data de 12 decembrie 2024 au fost organizate activit\u0103\u0163i de informare \u00een domeniul integrit\u0103\u021bii. Sesiunea a fost desf\u0103\u0219urat\u0103 de c\u0103tre [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":22395,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"translation":{"provider":"WPGlobus","version":"2.12.2","language":"gb","enabled_languages":["ro","gb"],"languages":{"ro":{"title":true,"content":true,"excerpt":false},"gb":{"title":false,"content":false,"excerpt":false}}},"acf":[],"_links":{"self":[{"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/22386"}],"collection":[{"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/comments?post=22386"}],"version-history":[{"count":4,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/22386\/revisions"}],"predecessor-version":[{"id":22397,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/22386\/revisions\/22397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/media\/22395"}],"wp:attachment":[{"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/media?parent=22386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/categories?post=22386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/tags?post=22386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}