{"id":22067,"date":"2024-11-28T13:37:05","date_gmt":"2024-11-28T11:37:05","guid":{"rendered":"https:\/\/academy.police.md\/?p=22067"},"modified":"2024-11-28T13:37:06","modified_gmt":"2024-11-28T11:37:06","slug":"cercul-stiintific-studentesc-areopag-s-a-alaturat-campaniei-16-zile-de-activism-impotriva-violentei-in-baza-de-gen","status":"publish","type":"post","link":"https:\/\/academy.police.md\/gb\/cercul-stiintific-studentesc-areopag-s-a-alaturat-campaniei-16-zile-de-activism-impotriva-violentei-in-baza-de-gen","title":{"rendered":"Cercul \u015etiin\u0163ific Studen\u0163esc \u201eAreopag\u201d s-a al\u0103turat Campaniei \u201e16 zile de activism \u00eempotriva violen\u0163ei \u00een baz\u0103 de gen\u201d"},"content":{"rendered":"\n<p>Cercul \u015etiin\u0163ific Studen\u0163esc \u201eAreopag\u201d al Catedrei Drept public, securitate a frontierei, migra\u021bie \u0219i azil a Academiei \u201e\u015etefan cel Mare\u201d s-a al\u0103turat Campaniei \u201e16 zile de activism \u00eempotriva violen\u0163ei \u00een baz\u0103 de gen\u201d.<\/p>\n\n\n\n<p>\u00cen perioada 25 noiembrie &#8211; 10 decembrie, \u00eentreaga lume marcheaz\u0103 Campania \u201e16 zile de activism \u00eempotriva violen\u0163ei \u00een baz\u0103 de gen\u201d. Este o ini\u0163iativ\u0103 anual\u0103, menit\u0103 s\u0103 pun\u0103 cap\u0103t violen\u0163ei \u00eempotriva femeilor.<\/p>\n\n\n\n<p>Astfel, la data de 27 noiembrie 2024, conduc\u0103torul cercului, \u00eempreun\u0103 cu membrii permanen\u0163i ai acestuia au desf\u0103\u015furat un Simpozion \u015ftiin\u0163ific cu genericul: \u201eNu e\u015fti singur\u0103! Uni\u0163i \u00eempotriva violen\u0163ei fa\u0163\u0103 de fete \u015fi femei\u201d. Obiectivul principal fiind sensibilizarea \u015fi familiarizarea studen\u0163ilor cu fenomenul violen\u0163ei asupra fetelor \u0219i femeilor, care este considerat o \u00eenc\u0103lcare grav\u0103 a drepturilor fundamentale ale omului, la nivel mondial.<\/p>\n\n\n\n<p>Sesiunea de referin\u0163\u0103 a fost organizat\u0103 \u00een trei ateliere de lucru, studen\u0163ii av\u00e2nd posibilitatea de a fi implica\u0163i \u00een mai multe activit\u0103\u0163i desf\u0103\u015furate cu scopul de a-\u015fi dezvolta nivelul de con\u015ftientizare privind problema violen\u0163ei \u00eempotriva fetelor \u015fi femeilor.<\/p>\n\n\n\n<p>\u00cen semn de solidaritate, pentru victimele violen\u021bei \u00een baz\u0103 de gen, pe tot parcursul campaniei, \u00een auditoriile de curs v-or fi afi\u015fate mesaje de informare privind violen\u0163a \u00een baz\u0103 de gen.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"854\" height=\"480\" src=\"\/wp-content\/uploads\/2024\/11\/1-8.jpg\" alt=\"\" data-id=\"22071\" data-full-url=\"\/wp-content\/uploads\/2024\/11\/1-8.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=22071\" class=\"wp-image-22071\" srcset=\"\/wp-content\/uploads\/2024\/11\/1-8.jpg 854w, \/wp-content\/uploads\/2024\/11\/1-8-300x169.jpg 300w, \/wp-content\/uploads\/2024\/11\/1-8-768x432.jpg 768w\" sizes=\"(max-width: 854px) 100vw, 854px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"\/wp-content\/uploads\/2024\/11\/20241127_153606-1024x768.jpg\" alt=\"\" data-id=\"22072\" data-full-url=\"\/wp-content\/uploads\/2024\/11\/20241127_153606-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=22072\" class=\"wp-image-22072\" srcset=\"\/wp-content\/uploads\/2024\/11\/20241127_153606-1024x768.jpg 1024w, \/wp-content\/uploads\/2024\/11\/20241127_153606-300x225.jpg 300w, \/wp-content\/uploads\/2024\/11\/20241127_153606-768x576.jpg 768w, \/wp-content\/uploads\/2024\/11\/20241127_153606-1536x1152.jpg 1536w, \/wp-content\/uploads\/2024\/11\/20241127_153606-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"942\" src=\"\/wp-content\/uploads\/2024\/11\/20241128_114856-1024x942.jpg\" alt=\"\" data-id=\"22073\" data-full-url=\"\/wp-content\/uploads\/2024\/11\/20241128_114856-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=22073\" class=\"wp-image-22073\" srcset=\"\/wp-content\/uploads\/2024\/11\/20241128_114856-1024x942.jpg 1024w, \/wp-content\/uploads\/2024\/11\/20241128_114856-300x276.jpg 300w, \/wp-content\/uploads\/2024\/11\/20241128_114856-768x706.jpg 768w, \/wp-content\/uploads\/2024\/11\/20241128_114856-1536x1412.jpg 1536w, \/wp-content\/uploads\/2024\/11\/20241128_114856-2048x1883.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"\/wp-content\/uploads\/2024\/11\/20241128_115101-768x1024.jpg\" alt=\"\" data-id=\"22074\" data-full-url=\"\/wp-content\/uploads\/2024\/11\/20241128_115101-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=22074\" class=\"wp-image-22074\" srcset=\"\/wp-content\/uploads\/2024\/11\/20241128_115101-768x1024.jpg 768w, \/wp-content\/uploads\/2024\/11\/20241128_115101-225x300.jpg 225w, \/wp-content\/uploads\/2024\/11\/20241128_115101-1152x1536.jpg 1152w, \/wp-content\/uploads\/2024\/11\/20241128_115101-1536x2048.jpg 1536w, \/wp-content\/uploads\/2024\/11\/20241128_115101-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"854\" height=\"480\" src=\"\/wp-content\/uploads\/2024\/11\/IMG-1d65f05c3d1471b535e58852901d3019-V.jpg\" alt=\"\" data-id=\"22075\" data-full-url=\"\/wp-content\/uploads\/2024\/11\/IMG-1d65f05c3d1471b535e58852901d3019-V.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=22075\" class=\"wp-image-22075\" srcset=\"\/wp-content\/uploads\/2024\/11\/IMG-1d65f05c3d1471b535e58852901d3019-V.jpg 854w, \/wp-content\/uploads\/2024\/11\/IMG-1d65f05c3d1471b535e58852901d3019-V-300x169.jpg 300w, \/wp-content\/uploads\/2024\/11\/IMG-1d65f05c3d1471b535e58852901d3019-V-768x432.jpg 768w\" sizes=\"(max-width: 854px) 100vw, 854px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"854\" height=\"480\" src=\"\/wp-content\/uploads\/2024\/11\/IMG-09d49700115417b69e4d607780c4f780-V.jpg\" alt=\"\" data-id=\"22076\" data-full-url=\"\/wp-content\/uploads\/2024\/11\/IMG-09d49700115417b69e4d607780c4f780-V.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=22076\" class=\"wp-image-22076\" srcset=\"\/wp-content\/uploads\/2024\/11\/IMG-09d49700115417b69e4d607780c4f780-V.jpg 854w, \/wp-content\/uploads\/2024\/11\/IMG-09d49700115417b69e4d607780c4f780-V-300x169.jpg 300w, \/wp-content\/uploads\/2024\/11\/IMG-09d49700115417b69e4d607780c4f780-V-768x432.jpg 768w\" sizes=\"(max-width: 854px) 100vw, 854px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"854\" height=\"480\" src=\"\/wp-content\/uploads\/2024\/11\/IMG-ec864c0c62c80118ea726d22f1f6cdb2-V.jpg\" alt=\"\" data-id=\"22077\" data-full-url=\"\/wp-content\/uploads\/2024\/11\/IMG-ec864c0c62c80118ea726d22f1f6cdb2-V.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=22077\" class=\"wp-image-22077\" srcset=\"\/wp-content\/uploads\/2024\/11\/IMG-ec864c0c62c80118ea726d22f1f6cdb2-V.jpg 854w, \/wp-content\/uploads\/2024\/11\/IMG-ec864c0c62c80118ea726d22f1f6cdb2-V-300x169.jpg 300w, \/wp-content\/uploads\/2024\/11\/IMG-ec864c0c62c80118ea726d22f1f6cdb2-V-768x432.jpg 768w\" sizes=\"(max-width: 854px) 100vw, 854px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"556\" src=\"\/wp-content\/uploads\/2024\/11\/P1260365-1024x556.jpg\" alt=\"\" data-id=\"22078\" data-full-url=\"\/wp-content\/uploads\/2024\/11\/P1260365-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=22078\" class=\"wp-image-22078\" srcset=\"\/wp-content\/uploads\/2024\/11\/P1260365-1024x556.jpg 1024w, \/wp-content\/uploads\/2024\/11\/P1260365-300x163.jpg 300w, \/wp-content\/uploads\/2024\/11\/P1260365-768x417.jpg 768w, \/wp-content\/uploads\/2024\/11\/P1260365-1536x833.jpg 1536w, \/wp-content\/uploads\/2024\/11\/P1260365-2048x1111.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"550\" src=\"\/wp-content\/uploads\/2024\/11\/P1260370-1024x550.jpg\" alt=\"\" data-id=\"22079\" data-full-url=\"\/wp-content\/uploads\/2024\/11\/P1260370-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=22079\" class=\"wp-image-22079\" srcset=\"\/wp-content\/uploads\/2024\/11\/P1260370-1024x550.jpg 1024w, \/wp-content\/uploads\/2024\/11\/P1260370-300x161.jpg 300w, \/wp-content\/uploads\/2024\/11\/P1260370-768x413.jpg 768w, \/wp-content\/uploads\/2024\/11\/P1260370-1536x825.jpg 1536w, \/wp-content\/uploads\/2024\/11\/P1260370-2048x1100.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<figure class=\"wp-block-gallery columns-0 is-cropped\"><ul class=\"blocks-gallery-grid\"><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Cercul \u015etiin\u0163ific Studen\u0163esc \u201eAreopag\u201d al Catedrei Drept public, securitate a frontierei, migra\u021bie \u0219i azil a Academiei \u201e\u015etefan cel Mare\u201d s-a al\u0103turat Campaniei \u201e16 zile de activism \u00eempotriva violen\u0163ei \u00een baz\u0103 [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":22068,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"translation":{"provider":"WPGlobus","version":"2.12.2","language":"gb","enabled_languages":["ro","gb"],"languages":{"ro":{"title":true,"content":true,"excerpt":false},"gb":{"title":false,"content":false,"excerpt":false}}},"acf":[],"_links":{"self":[{"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/22067"}],"collection":[{"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/comments?post=22067"}],"version-history":[{"count":2,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/22067\/revisions"}],"predecessor-version":[{"id":22081,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/22067\/revisions\/22081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/media\/22068"}],"wp:attachment":[{"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/media?parent=22067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/categories?post=22067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/tags?post=22067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}