{"id":17236,"date":"2024-01-23T10:46:02","date_gmt":"2024-01-23T08:46:02","guid":{"rendered":"https:\/\/academy.police.md\/?p=17236"},"modified":"2024-01-23T10:46:03","modified_gmt":"2024-01-23T08:46:03","slug":"proiectul-academia-junior-club-revine-in-forta-in-anul-2024","status":"publish","type":"post","link":"https:\/\/academy.police.md\/gb\/proiectul-academia-junior-club-revine-in-forta-in-anul-2024","title":{"rendered":"Proiectul Academia \u201eJunior Club\u201d revine \u00een for\u0163\u0103, \u00een anul 2024"},"content":{"rendered":"\n<p>La data de 19 ianuarie curent, Academia \u201e\u015etefan cel Mare\u201d a g\u0103zduit primii participan\u021bi ai anului 2024 la Proiectul Academia \u201eJunior Club\u201d, delega\u021bi din cadrul Liceului Teoretic \u201eTitu Maiorescu\u201d din Chi\u0219in\u0103u, care \u00ee\u0219i fac studiile \u00een clasa a IV-a.<\/p>\n\n\n\n<p> Vizita a inclus un itinerar de informare cu obiectivele \u015fi activit\u0103\u0163ile institu\u0163iei precum \u015fi instruiri pe mai multe domenii din cadrul modulelor cu urm\u0103toarele tematici:<\/p>\n\n\n\n<ul><li>Atelierul 1. Expozi\u0163ie de armament. Instructaj cu privire la regulile de m\u00e2nuire a armei de foc. Elemente de autoap\u0103rare \u015fi de imobilizare a adversarului. Tir electronic;<\/li><li>Atelierul 2. Simularea situa\u0163ional\u0103 \u015fi identificarea urmelor de sustragere a bunurilor personale;<\/li><li>Atelierul 3. Academia \u00een imagini \u2013 vizionarea filmelor promo\u0163ionale ale Academiei \u201e\u015etefan cel MAre\u201d.<\/li><\/ul>\n\n\n\n<p>Totodat\u0103, elevii au fost familiariza\u0163i cu domeniul de aplicare a legii \u015fi oferta educa\u0163ional\u0103 a institu\u0163iei, fiind ghida\u0163i s\u0103 opteze \u00een viitor \u00een favoarea profesiunilor din\u00a0 cadrul sistemului afacerilor interne.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2024\/01\/IMG_1-1024x683.jpg\" alt=\"\" data-id=\"17238\" data-full-url=\"\/wp-content\/uploads\/2024\/01\/IMG_1.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=17238\" class=\"wp-image-17238\" srcset=\"\/wp-content\/uploads\/2024\/01\/IMG_1-1024x683.jpg 1024w, \/wp-content\/uploads\/2024\/01\/IMG_1-300x200.jpg 300w, \/wp-content\/uploads\/2024\/01\/IMG_1-768x512.jpg 768w, \/wp-content\/uploads\/2024\/01\/IMG_1.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2024\/01\/IMG_7711-1024x683.jpg\" alt=\"\" data-id=\"17239\" data-full-url=\"\/wp-content\/uploads\/2024\/01\/IMG_7711.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=17239\" class=\"wp-image-17239\" srcset=\"\/wp-content\/uploads\/2024\/01\/IMG_7711-1024x683.jpg 1024w, \/wp-content\/uploads\/2024\/01\/IMG_7711-300x200.jpg 300w, \/wp-content\/uploads\/2024\/01\/IMG_7711-768x512.jpg 768w, \/wp-content\/uploads\/2024\/01\/IMG_7711.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2024\/01\/IMG_7728-1024x683.jpg\" alt=\"\" data-id=\"17240\" data-full-url=\"\/wp-content\/uploads\/2024\/01\/IMG_7728.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=17240\" class=\"wp-image-17240\" srcset=\"\/wp-content\/uploads\/2024\/01\/IMG_7728-1024x683.jpg 1024w, \/wp-content\/uploads\/2024\/01\/IMG_7728-300x200.jpg 300w, \/wp-content\/uploads\/2024\/01\/IMG_7728-768x512.jpg 768w, \/wp-content\/uploads\/2024\/01\/IMG_7728.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2024\/01\/IMG_7734-1024x683.jpg\" alt=\"\" data-id=\"17241\" data-full-url=\"\/wp-content\/uploads\/2024\/01\/IMG_7734.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=17241\" class=\"wp-image-17241\" srcset=\"\/wp-content\/uploads\/2024\/01\/IMG_7734-1024x683.jpg 1024w, \/wp-content\/uploads\/2024\/01\/IMG_7734-300x200.jpg 300w, \/wp-content\/uploads\/2024\/01\/IMG_7734-768x512.jpg 768w, \/wp-content\/uploads\/2024\/01\/IMG_7734.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2024\/01\/IMG_7782-1024x683.jpg\" alt=\"\" data-id=\"17242\" data-full-url=\"\/wp-content\/uploads\/2024\/01\/IMG_7782.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=17242\" class=\"wp-image-17242\" srcset=\"\/wp-content\/uploads\/2024\/01\/IMG_7782-1024x683.jpg 1024w, \/wp-content\/uploads\/2024\/01\/IMG_7782-300x200.jpg 300w, \/wp-content\/uploads\/2024\/01\/IMG_7782-768x512.jpg 768w, \/wp-content\/uploads\/2024\/01\/IMG_7782.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2024\/01\/IMG_7803-1024x683.jpg\" alt=\"\" data-id=\"17243\" data-full-url=\"\/wp-content\/uploads\/2024\/01\/IMG_7803.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=17243\" class=\"wp-image-17243\" srcset=\"\/wp-content\/uploads\/2024\/01\/IMG_7803-1024x683.jpg 1024w, \/wp-content\/uploads\/2024\/01\/IMG_7803-300x200.jpg 300w, \/wp-content\/uploads\/2024\/01\/IMG_7803-768x512.jpg 768w, \/wp-content\/uploads\/2024\/01\/IMG_7803.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2024\/01\/IMG_7823-1024x683.jpg\" alt=\"\" data-id=\"17244\" data-full-url=\"\/wp-content\/uploads\/2024\/01\/IMG_7823.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=17244\" class=\"wp-image-17244\" srcset=\"\/wp-content\/uploads\/2024\/01\/IMG_7823-1024x683.jpg 1024w, \/wp-content\/uploads\/2024\/01\/IMG_7823-300x200.jpg 300w, \/wp-content\/uploads\/2024\/01\/IMG_7823-768x512.jpg 768w, \/wp-content\/uploads\/2024\/01\/IMG_7823.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2024\/01\/IMG_7845-1024x683.jpg\" alt=\"\" data-id=\"17245\" data-full-url=\"\/wp-content\/uploads\/2024\/01\/IMG_7845.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=17245\" class=\"wp-image-17245\" srcset=\"\/wp-content\/uploads\/2024\/01\/IMG_7845-1024x683.jpg 1024w, \/wp-content\/uploads\/2024\/01\/IMG_7845-300x200.jpg 300w, \/wp-content\/uploads\/2024\/01\/IMG_7845-768x512.jpg 768w, \/wp-content\/uploads\/2024\/01\/IMG_7845.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2024\/01\/IMG_7866-1024x683.jpg\" alt=\"\" data-id=\"17246\" data-full-url=\"\/wp-content\/uploads\/2024\/01\/IMG_7866.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=17246\" class=\"wp-image-17246\" srcset=\"\/wp-content\/uploads\/2024\/01\/IMG_7866-1024x683.jpg 1024w, \/wp-content\/uploads\/2024\/01\/IMG_7866-300x200.jpg 300w, \/wp-content\/uploads\/2024\/01\/IMG_7866-768x512.jpg 768w, \/wp-content\/uploads\/2024\/01\/IMG_7866.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2024\/01\/IMG_7875-1024x683.jpg\" alt=\"\" data-id=\"17247\" data-full-url=\"\/wp-content\/uploads\/2024\/01\/IMG_7875.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=17247\" class=\"wp-image-17247\" srcset=\"\/wp-content\/uploads\/2024\/01\/IMG_7875-1024x683.jpg 1024w, \/wp-content\/uploads\/2024\/01\/IMG_7875-300x200.jpg 300w, \/wp-content\/uploads\/2024\/01\/IMG_7875-768x512.jpg 768w, \/wp-content\/uploads\/2024\/01\/IMG_7875.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La data de 19 ianuarie curent, Academia \u201e\u015etefan cel Mare\u201d a g\u0103zduit primii participan\u021bi ai anului 2024 la Proiectul Academia \u201eJunior Club\u201d, delega\u021bi din cadrul Liceului Teoretic \u201eTitu Maiorescu\u201d din [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":17237,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"translation":{"provider":"WPGlobus","version":"2.12.2","language":"gb","enabled_languages":["ro","gb"],"languages":{"ro":{"title":true,"content":true,"excerpt":false},"gb":{"title":false,"content":false,"excerpt":false}}},"acf":[],"_links":{"self":[{"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/17236"}],"collection":[{"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/comments?post=17236"}],"version-history":[{"count":2,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/17236\/revisions"}],"predecessor-version":[{"id":17249,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/17236\/revisions\/17249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/media\/17237"}],"wp:attachment":[{"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/media?parent=17236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/categories?post=17236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/tags?post=17236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}