{"id":13253,"date":"2023-06-27T10:54:54","date_gmt":"2023-06-27T07:54:54","guid":{"rendered":"https:\/\/academy.police.md\/?p=13253"},"modified":"2023-06-27T10:57:53","modified_gmt":"2023-06-27T07:57:53","slug":"excelente-apreciabile-pe-taramul-sportului-international","status":"publish","type":"post","link":"https:\/\/academy.police.md\/gb\/excelente-apreciabile-pe-taramul-sportului-international","title":{"rendered":"Excelen\u021be apreciabile pe t\u0103r\u00e2mul sportului interna\u021bional"},"content":{"rendered":"\n<p>Colectivul Academiei \u201e\u0218tefan cel Mare\u201d, cu admira\u021bie, urm\u0103re\u0219te evolu\u021bia sportivului moldovean pe arena interna\u021bional\u0103 \u2013 studentul anului III de studii al Facult\u0103\u021bii Drept, administra\u021bie, ordine \u0219i securitate public\u0103, Artiom Livadari evolueaz\u0103, \u00een aceste zile, la European Games <a href=\"https:\/\/en.wikipedia.org\/wiki\/Krak%C3%B3w\">Krak\u00f3w<\/a>&#8211;<a href=\"https:\/\/en.wikipedia.org\/wiki\/Lesser_Poland_Voivodeship\">Ma\u0142opolska<\/a> 2023 \u00een Polonia.<\/p>\n\n\n\n<p>Astfel, duminic\u0103, 25 iunie lupt\u0103torul de muaythai s-a calificat \u00een semifinal\u0103, dup\u0103 ce l-a \u00eenvins pe medaliatul cu bronz de la ultimul Campionat Mondial, francezul Bakhouche Chareuf, iar luni, 26 iunie a ob\u021binut victorie \u00een lupta cu sportivul turc Enis Yunusoglu, calific\u00e2ndu-se \u00een finala Jocurilor Europene.<\/p>\n\n\n\n<p>Ast\u0103zi, 27 iunie Artiom Livadari se va \u00eent\u00e2lni \u00een patrulaterul de final\u0103 cu ucraineanul Yehor Skurikhin.<\/p>\n\n\n\n<p>To\u021bi colegii s\u0103i de la Academia \u201e\u0218tefan cel Mare\u201d, colectivul institu\u021biei, precum \u0219i echipa catedrei de profil \u021bin pumnii pentru Artiom! Baft\u0103 \u0219i caracter \u00een final\u0103!<\/p>\n\n\n\n<p><a href=\"https:\/\/m.facebook.com\/story.php?story_fbid=pfbid0wzf4krAmTz2yyiuDBg5aUMraeW82ddx42nzfGU2Ax1Vv6DXXnTWqrDGEUC28DDrDl&amp;id=100064582544050&amp;mibextid=Nif5oz\">Imaginile au fost preluate de pe pagina Facebook \u201eOlympic Moldova\u201d.<\/a><\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851540243-1024x683.jpg\" alt=\"\" data-id=\"13263\" data-full-url=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851540243.jpg\" data-link=\"https:\/\/academy.police.md\/fb_img_1687851540243\" class=\"wp-image-13263\" srcset=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851540243-1024x683.jpg 1024w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851540243-300x200.jpg 300w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851540243-768x512.jpg 768w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851540243.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851533114-1024x683.jpg\" alt=\"\" data-id=\"13262\" data-full-url=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851533114.jpg\" data-link=\"https:\/\/academy.police.md\/fb_img_1687851533114\" class=\"wp-image-13262\" srcset=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851533114-1024x683.jpg 1024w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851533114-300x200.jpg 300w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851533114-768x512.jpg 768w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851533114.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"979\" height=\"653\" src=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851529625.jpg\" alt=\"\" data-id=\"13261\" data-full-url=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851529625.jpg\" data-link=\"https:\/\/academy.police.md\/fb_img_1687851529625\" class=\"wp-image-13261\" srcset=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851529625.jpg 979w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851529625-300x200.jpg 300w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851529625-768x512.jpg 768w\" sizes=\"(max-width: 979px) 100vw, 979px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851522246-1024x683.jpg\" alt=\"\" data-id=\"13260\" data-full-url=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851522246.jpg\" data-link=\"https:\/\/academy.police.md\/fb_img_1687851522246\" class=\"wp-image-13260\" srcset=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851522246-1024x683.jpg 1024w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851522246-300x200.jpg 300w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851522246-768x512.jpg 768w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851522246.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851514565-1024x683.jpg\" alt=\"\" data-id=\"13259\" data-full-url=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851514565.jpg\" data-link=\"https:\/\/academy.police.md\/fb_img_1687851514565\" class=\"wp-image-13259\" srcset=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851514565-1024x683.jpg 1024w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851514565-300x200.jpg 300w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851514565-768x512.jpg 768w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851514565.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851504134-1024x683.jpg\" alt=\"\" data-id=\"13258\" data-full-url=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851504134.jpg\" data-link=\"https:\/\/academy.police.md\/fb_img_1687851504134\" class=\"wp-image-13258\" srcset=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851504134-1024x683.jpg 1024w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851504134-300x200.jpg 300w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851504134-768x512.jpg 768w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851504134.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851496233-1024x683.jpg\" alt=\"\" data-id=\"13257\" data-full-url=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851496233.jpg\" data-link=\"https:\/\/academy.police.md\/fb_img_1687851496233\" class=\"wp-image-13257\" srcset=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851496233-1024x683.jpg 1024w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851496233-300x200.jpg 300w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851496233-768x512.jpg 768w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851496233.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851491410-1024x683.jpg\" alt=\"\" data-id=\"13256\" data-full-url=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851491410.jpg\" data-link=\"https:\/\/academy.police.md\/fb_img_1687851491410\" class=\"wp-image-13256\" srcset=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851491410-1024x683.jpg 1024w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851491410-300x200.jpg 300w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851491410-768x512.jpg 768w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851491410.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1023\" height=\"681\" src=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851484466.jpg\" alt=\"\" data-id=\"13255\" data-full-url=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851484466.jpg\" data-link=\"https:\/\/academy.police.md\/fb_img_1687851484466\" class=\"wp-image-13255\" srcset=\"\/wp-content\/uploads\/2023\/06\/FB_IMG_1687851484466.jpg 1023w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851484466-300x200.jpg 300w, \/wp-content\/uploads\/2023\/06\/FB_IMG_1687851484466-768x511.jpg 768w\" sizes=\"(max-width: 1023px) 100vw, 1023px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Colectivul Academiei \u201e\u0218tefan cel Mare\u201d, cu admira\u021bie, urm\u0103re\u0219te evolu\u021bia sportivului moldovean pe arena interna\u021bional\u0103 \u2013 studentul anului III de studii al Facult\u0103\u021bii Drept, administra\u021bie, ordine \u0219i securitate public\u0103, Artiom Livadari [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":13255,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"translation":{"provider":"WPGlobus","version":"2.12.2","language":"gb","enabled_languages":["ro","gb"],"languages":{"ro":{"title":true,"content":true,"excerpt":false},"gb":{"title":false,"content":false,"excerpt":false}}},"acf":[],"_links":{"self":[{"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/13253"}],"collection":[{"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/comments?post=13253"}],"version-history":[{"count":2,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/13253\/revisions"}],"predecessor-version":[{"id":13266,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/13253\/revisions\/13266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/media\/13255"}],"wp:attachment":[{"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/media?parent=13253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/categories?post=13253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/academy.police.md\/gb\/wp-json\/wp\/v2\/tags?post=13253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}